{"id":5769,"date":"2026-08-13T19:14:51","date_gmt":"2026-08-14T00:14:51","guid":{"rendered":"https:\/\/www.tyrellchemical.com\/details-du-produit-tc-7100\/"},"modified":"2026-08-20T08:16:48","modified_gmt":"2026-08-20T13:16:48","slug":"details-du-produit-tc-7100","status":"publish","type":"page","link":"https:\/\/www.tyrellchemical.com\/fr\/details-du-produit-tc-7100\/","title":{"rendered":"D\u00e9tails du produit &#8211; TC 7100"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.18.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb positioning=\u00a0\u00bbnone\u00a0\u00bb position_origin_f=\u00a0\u00bbtop_center\u00a0\u00bb custom_padding=\u00a0\u00bb0px|0px|0px|0px|true|true\u00a0\u00bb sticky_position=\u00a0\u00bbtop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__sticky_enabled=\u00a0\u00bbon|desktop\u00a0\u00bb custom_padding__hover_enabled=\u00a0\u00bboff|desktop\u00a0\u00bb custom_padding__sticky=\u00a0\u00bb5px||5px||true|true\u00a0\u00bb][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.27.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.27.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/www.tyrellchemical.com\/wp-content\/uploads\/2026\/07\/TC-7100-Hero-image.png\u00a0\u00bb title_text=\u00a0\u00bbTC 7100 Hero image\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/www.tyrellchemical.com\/wp-content\/uploads\/2026\/07\/TC-7200-Benefits.png\u00a0\u00bb title_text=\u00a0\u00bbTC 7200 Benefits\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/www.tyrellchemical.com\/wp-content\/uploads\/2026\/07\/TC-7200_Technical_Specifications.png\u00a0\u00bb title_text=\u00a0\u00bbTC-7200_Technical_Specifications\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/www.tyrellchemical.com\/wp-content\/uploads\/2026\/07\/TC-7200-Applications.png\u00a0\u00bb title_text=\u00a0\u00bbTC-7200 Applications\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.27.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_heading title=\u00a0\u00bbCaract\u00e9ristiques du produit\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb title_text_align=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_heading][et_pb_text _builder_version=\u00a0\u00bb4.27.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb23px\u00a0\u00bb text_letter_spacing=\u00a0\u00bb2px\u00a0\u00bb text_line_height=\u00a0\u00bb1.9em\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<ul>\n<li>Bonne fluidit\u00e9, circule facilement dans le syst\u00e8me de r\u00e9gulation de la temp\u00e9rature pour dissiper la chaleur.<\/li>\n<li>Excellente isolation \u00e9lectrique et excellente conductivit\u00e9 thermique.<\/li>\n<li>Son point d&rsquo;\u00e9bullition \u00e9tant tr\u00e8s mod\u00e9r\u00e9, un processus d&rsquo;\u00e9vaporation se produit pendant le fonctionnement ; la chaleur d&rsquo;\u00e9vaporation est alors utilis\u00e9e pour \u00e9vacuer la chaleur, ce qui permet d&rsquo;assurer un fonctionnement stable et normal des \u00e9l\u00e9ments chauffants.<\/li>\n<li>Chimiquement inerte et thermiquement stable, ce produit peut \u00eatre largement utilis\u00e9 dans divers proc\u00e9d\u00e9s de dissipation thermique \u00e0 contr\u00f4le de temp\u00e9rature<br \/>.<\/li>\n<li>Bonne compatibilit\u00e9 avec les mat\u00e9riaux ; ne r\u00e9agit pas avec la plupart des m\u00e9taux, des plastiques et des polym\u00e8res.<\/li>\n<li>Non explosif, sans point d&rsquo;\u00e9clair.<\/li>\n<li>Tr\u00e8s faible tension superficielle, haute perm\u00e9abilit\u00e9.<\/li>\n<li>Bonne fluidit\u00e9, circule bien dans le syst\u00e8me de r\u00e9gulation de la temp\u00e9rature pour dissiper la chaleur.<\/li>\n<li>Non toxique, non dangereux et non irritant.<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_heading title=\u00a0\u00bbT\u00e9l\u00e9charger\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb title_text_align=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_heading][et_pb_image src=\u00a0\u00bbhttps:\/\/www.tyrellchemical.com\/wp-content\/uploads\/2026\/07\/Download-TDS.png\u00a0\u00bb title_text=\u00a0\u00bbDownload TDS\u00a0\u00bb url=\u00a0\u00bbhttps:\/\/www.tyrellchemical.com\/wp-content\/uploads\/2026\/08\/TC-7100-.pdf\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_image src=\u00a0\u00bbhttps:\/\/www.tyrellchemical.com\/wp-content\/uploads\/2026\/07\/Download-SDS.png\u00a0\u00bb title_text=\u00a0\u00bbDownload SDS\u00a0\u00bb url=\u00a0\u00bbhttps:\/\/www.tyrellchemical.com\/wp-content\/uploads\/2026\/08\/Safety-Data-Sheet-TC-7100-1.pdf\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; module_id=\u00a0\u00bbcontact\u00a0\u00bb _builder_version=\u00a0\u00bb4.18.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb custom_padding=\u00a0\u00bb||10px||false|false\u00a0\u00bb border_width_top_tablet=\u00a0\u00bb1px\u00a0\u00bb border_width_top_phone=\u00a0\u00bb1px\u00a0\u00bb border_width_top_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb border_color_top_tablet=\u00a0\u00bb#303030&Prime; border_color_top_phone=\u00a0\u00bb#303030&Prime; border_color_top_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.18.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_main_element=\u00a0\u00bbmargin:auto\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.18.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.18.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#083DAD\u00a0\u00bb header_2_font=\u00a0\u00bbMuller Bold|700|||||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#083DAD\u00a0\u00bb header_2_font_size=\u00a0\u00bb38px\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb38px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb25px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>CONTACTEZ-NOUS<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.18.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbMuller Regular||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#333333&Prime; link_font=\u00a0\u00bbMuller Bold|700|||||||\u00a0\u00bb link_text_color=\u00a0\u00bb#333333&Prime; header_3_font=\u00a0\u00bbMuller Bold|700|||||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#083DAD\u00a0\u00bb header_3_font_size=\u00a0\u00bb20px\u00a0\u00bb header_3_text_color_tablet=\u00a0\u00bb#083DAD\u00a0\u00bb header_3_text_color_phone=\u00a0\u00bb#083DAD\u00a0\u00bb header_3_text_color_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<div style=\"display: flex; width: 100%;\">\n<div style=\"width: 50%;\">\n<h3>Adresse<\/h3>\n<p>One Alhambra Plaza,<br \/>, PH, \u00e9tage<br \/>, Coral Gables, FL 33134<\/p>\n<\/div>\n<div style=\"width: 50%;\">\n<h3>Contact<\/h3>\n<p><a href=\"mailto:info@tyrellchem.com. \">info@tyrellchem.com<\/a><br \/><a href=\"tel:7866330019\">786-633-0019<\/a><\/p>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_image src=\u00a0\u00bbhttps:\/\/www.tyrellchemical.com\/wp-content\/uploads\/2022\/09\/Horizontal_Indigo.png\u00a0\u00bb alt=\u00a0\u00bbLogo Tyrell\u00a0\u00bb title_text=\u00a0\u00bbTyrell Logo\u00a0\u00bb _builder_version=\u00a0\u00bb4.18.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb100px\u00a0\u00bb width_tablet=\u00a0\u00bb150px\u00a0\u00bb width_phone=\u00a0\u00bb149px\u00a0\u00bb width_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.18.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_main_element=\u00a0\u00bbmargin:auto\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_contact_form email=\u00a0\u00bbinfo@tyrellchem.com\u00a0\u00bb custom_message=\u00a0\u00bbName: %%Name%%||et_pb_line_break_holder||Email: %%Email%%||et_pb_line_break_holder||Subject: %%Subject%%||et_pb_line_break_holder||Message: %%Message%% ||et_pb_line_break_holder||\u00a0\u00bb _builder_version=\u00a0\u00bb4.18.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb _unique_id=\u00a0\u00bbc670e2b8-5f86-4db2-9f2a-4187f295b4d3&Prime; form_field_background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb form_field_text_color=\u00a0\u00bb#083DAD\u00a0\u00bb form_field_focus_background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb form_field_focus_text_color=\u00a0\u00bb#083DAD\u00a0\u00bb captcha_font=\u00a0\u00bbMuller Regular||||||||\u00a0\u00bb captcha_text_color=\u00a0\u00bb#083DAD\u00a0\u00bb captcha_font_size=\u00a0\u00bb16px\u00a0\u00bb captcha_letter_spacing=\u00a0\u00bb2px\u00a0\u00bb form_field_font=\u00a0\u00bbMuller Regular||||||||\u00a0\u00bb form_field_text_align=\u00a0\u00bbleft\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb16px\u00a0\u00bb button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_bg_color=\u00a0\u00bb#083DAD\u00a0\u00bb button_border_width=\u00a0\u00bb1px\u00a0\u00bb button_border_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_border_radius=\u00a0\u00bb5px\u00a0\u00bb button_font=\u00a0\u00bbMuller Bold|700|||||||\u00a0\u00bb button_icon=\u00a0\u00bb\ue076||divi||400&Prime; border_radii=\u00a0\u00bbon|5px|5px|5px|5px\u00a0\u00bb border_width_all=\u00a0\u00bb1px\u00a0\u00bb border_color_all=\u00a0\u00bb#083DAD\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_contact_field field_id=\u00a0\u00bbName\u00a0\u00bb field_title=\u00a0\u00bbName\u00a0\u00bb _builder_version=\u00a0\u00bb4.18.0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bbEmail\u00a0\u00bb field_title=\u00a0\u00bbEmail Address\u00a0\u00bb field_type=\u00a0\u00bbemail\u00a0\u00bb _builder_version=\u00a0\u00bb4.18.0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bbSubject\u00a0\u00bb field_title=\u00a0\u00bbsubject\u00a0\u00bb required_mark=\u00a0\u00bboff\u00a0\u00bb fullwidth_field=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.18.0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bbMessage\u00a0\u00bb field_title=\u00a0\u00bbMessage\u00a0\u00bb field_type=\u00a0\u00bbtext\u00a0\u00bb fullwidth_field=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb][\/et_pb_contact_field][\/et_pb_contact_form][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.18.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||true|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.18.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb5px||5px||true|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.18.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.18.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbMuller Regular||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]\u00a92022 Tyrell Chemical[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bonne fluidit\u00e9, circule facilement dans le syst\u00e8me de r\u00e9gulation de la temp\u00e9rature pour dissiper la chaleur. Excellente isolation \u00e9lectrique et excellente conductivit\u00e9 thermique. Son point d&rsquo;\u00e9bullition \u00e9tant tr\u00e8s mod\u00e9r\u00e9, un processus d&rsquo;\u00e9vaporation se produit pendant le fonctionnement ; la chaleur d&rsquo;\u00e9vaporation est alors utilis\u00e9e pour \u00e9vacuer la chaleur, ce qui permet d&rsquo;assurer un fonctionnement stable [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-5769","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.tyrellchemical.com\/fr\/wp-json\/wp\/v2\/pages\/5769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tyrellchemical.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.tyrellchemical.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.tyrellchemical.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tyrellchemical.com\/fr\/wp-json\/wp\/v2\/comments?post=5769"}],"version-history":[{"count":1,"href":"https:\/\/www.tyrellchemical.com\/fr\/wp-json\/wp\/v2\/pages\/5769\/revisions"}],"predecessor-version":[{"id":6371,"href":"https:\/\/www.tyrellchemical.com\/fr\/wp-json\/wp\/v2\/pages\/5769\/revisions\/6371"}],"wp:attachment":[{"href":"https:\/\/www.tyrellchemical.com\/fr\/wp-json\/wp\/v2\/media?parent=5769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}