{"id":2259,"date":"2022-09-29T18:09:45","date_gmt":"2022-09-29T23:09:45","guid":{"rendered":"http:\/\/www.tyrellchemical.com\/la-nostra-azienda\/"},"modified":"2022-12-01T05:31:19","modified_gmt":"2022-12-01T10:31:19","slug":"la-nostra-azienda","status":"publish","type":"page","link":"https:\/\/www.tyrellchemical.com\/it\/la-nostra-azienda\/","title":{"rendered":"La nostra azienda"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;rgba(0,0,0,0.2) 0%|rgba(0,0,0,0.1) 100%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/www.tyrellchemical.com\/wp-content\/uploads\/2022\/09\/about-us.jpg&#8221; min_height=&#8221;80vh&#8221; min_height_tablet=&#8221;50vh&#8221; min_height_phone=&#8221;50vh&#8221; min_height_last_edited=&#8221;on|phone&#8221; custom_css_main_element=&#8221;display:flex;||margin:auto;&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; max_width=&#8221;2560px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text content_tablet=&#8221;<\/p>\n<h2><b>La nostra azienda<\/b><\/h2>\n<p>&#8221; content_phone=&#8221;<\/p>\n<h2><b>Il nostro<br \/>Azienda<\/b><\/h2>\n<p>&#8221; content_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;Muller Bold|700|||||||&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;52px&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; header_2_font_size_tablet=&#8221;52px&#8221; header_2_font_size_phone=&#8221;40px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><b>La nostra azienda<\/b><\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;90deg&#8221; background_color_gradient_stops=&#8221;#ffffff 22%|rgba(41,196,169,0) 24%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/www.tyrellchemical.com\/wp-content\/uploads\/2022\/09\/28.jpg&#8221; background_position=&#8221;center_right&#8221; custom_margin=&#8221;50px||50px||false|false&#8221; custom_margin_tablet=&#8221;50px||50px||false|false&#8221; custom_margin_phone=&#8221;30px||30px||true|false&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; background_last_edited=&#8221;on|tablet&#8221; background_color_gradient_overlays_image_tablet=&#8221;off&#8221; background_size_tablet=&#8221;contain&#8221; background_position_tablet=&#8221;top_center&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; make_equal=&#8221;on&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; width_tablet=&#8221;80%&#8221; width_phone=&#8221;80%&#8221; width_last_edited=&#8221;on|tablet&#8221; max_width=&#8221;2560px&#8221; custom_padding_tablet=&#8221;200px||||false|false&#8221; custom_padding_phone=&#8221;100px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; custom_padding=&#8221;70px|5%|70px|5%|true|false&#8221; custom_padding_tablet=&#8221;40px||40px||true|false&#8221; custom_padding_phone=&#8221;40px||40px||true|false&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; custom_css_main_element=&#8221;width:65%!important&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_color=&#8221;rgba(0,0,0,0.5)&#8221; global_colors_info=&#8221;{}&#8221; custom_css_main_element_last_edited=&#8221;on|tablet&#8221; custom_css_main_element_tablet=&#8221;width:100%!important&#8221; custom_css_main_element_phone=&#8221;width:100%!important&#8221;][et_pb_text _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Muller Regular||||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;16px&#8221; header_2_font=&#8221;Muller Bold|700|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#083dad&#8221; header_2_font_size=&#8221;38px&#8221; text_orientation=&#8221;center&#8221; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;||10px||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; header_2_font_size_tablet=&#8221;38px&#8221; header_2_font_size_phone=&#8221;25px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Reazioni <span style=\"color: #25b2ee;\">trasformate<\/span><\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#083DAD&#8221; text_font_size=&#8221;20px&#8221; header_2_font=&#8221;Muller Bold|700|||||||&#8221; header_2_text_color=&#8221;#25B2EE&#8221; header_2_font_size=&#8221;38px&#8221; custom_margin=&#8221;||10px||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; text_font_size_tablet=&#8221;20px&#8221; text_font_size_phone=&#8221;18px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><b>Tyrell Chemical produce soluzioni mirate per sostenere e trasformare la catena di fornitura dei fluidi per il trasferimento di calore.<\/b><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Muller Regular||||||||&#8221; text_text_color=&#8221;#333333&#8243; text_font_size=&#8221;16px&#8221; animation_style=&#8221;fade&#8221; animation_direction=&#8221;bottom&#8221; text_font_size_tablet=&#8221;16px&#8221; text_font_size_phone=&#8221;14px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\">La nostra azienda offre un&#8217;ampia gamma di fluidi per il trasferimento termico che sono chimicamente e termicamente stabili in una vasta gamma di applicazioni e condizioni. Tyrell Chemical ha rapporti decennali con i professionisti del settore che ci permettono di produrre prodotti chimici di alta qualit\u00e0 specifici per il settore, in sostituzione di produttori simili o per consentire la diversificazione della catena di approvvigionamento. Il nostro team comprende personale sia negli Stati Uniti che all&#8217;estero, che ci permette di essere presenti sul posto e di avere una catena di approvvigionamento da punto a punto. Sia che provenga dai nostri magazzini nazionali o direttamente dal nostro stabilimento di produzione, Tyrell Chemical \u00e8 in grado di fornire forniture garantite sia a livello locale che all&#8217;estero.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; background_enable_image=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;90deg&#8221; background_color_gradient_stops=&#8221;rgba(255,255,255,0) 70%|#ffffff 70%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/www.tyrellchemical.com\/wp-content\/uploads\/2022\/09\/20.jpg&#8221; hover_enabled=&#8221;0&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; title_text=&#8221;20&#8243; sticky_enabled=&#8221;0&#8243;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; custom_padding_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;2560px&#8221; module_alignment=&#8221;right&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; custom_padding=&#8221;70px|5%|70px|5%|true|false&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_color=&#8221;rgba(0,0,0,0.5)&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Muller Regular||||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;16px&#8221; header_2_font=&#8221;Muller Bold|700|||||||&#8221; header_2_text_color=&#8221;#083dad&#8221; header_2_font_size=&#8221;38px&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Dichiarazione di missione<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Muller Regular||||||||&#8221; text_text_color=&#8221;#333333&#8243; text_font_size=&#8221;16px&#8221; custom_padding=&#8221;||||false|false&#8221; animation_style=&#8221;fade&#8221; animation_direction=&#8221;left&#8221; global_colors_info=&#8221;{}&#8221;]Tyrell Chemical mira a fornire prodotti chimici di alta qualit\u00e0 per applicazioni produttive specializzate. Siamo impegnati nella gestione del controllo di qualit\u00e0 e in pratiche sicure per l&#8217;ambiente e miriamo a fornire soluzioni mirate che sostengano e diversifichino le catene di fornitura dei fluidi per il trasferimento termico.  [\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La nostra aziendaReazioni trasformateTyrell Chemical produce soluzioni mirate per sostenere e trasformare la catena di fornitura dei fluidi per il trasferimento di calore.La nostra azienda offre un&#8217;ampia gamma di fluidi per il trasferimento termico che sono chimicamente e termicamente stabili in una vasta gamma di applicazioni e condizioni. Tyrell Chemical ha rapporti decennali con i [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-2259","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.tyrellchemical.com\/it\/wp-json\/wp\/v2\/pages\/2259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tyrellchemical.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.tyrellchemical.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.tyrellchemical.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tyrellchemical.com\/it\/wp-json\/wp\/v2\/comments?post=2259"}],"version-history":[{"count":8,"href":"https:\/\/www.tyrellchemical.com\/it\/wp-json\/wp\/v2\/pages\/2259\/revisions"}],"predecessor-version":[{"id":2903,"href":"https:\/\/www.tyrellchemical.com\/it\/wp-json\/wp\/v2\/pages\/2259\/revisions\/2903"}],"wp:attachment":[{"href":"https:\/\/www.tyrellchemical.com\/it\/wp-json\/wp\/v2\/media?parent=2259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}